{"id":29859,"date":"2025-01-02T17:52:00","date_gmt":"2025-01-02T16:52:00","guid":{"rendered":"https:\/\/bamigra.de\/?post_type=tribe_events&#038;p=29859"},"modified":"2025-01-02T17:52:00","modified_gmt":"2025-01-02T16:52:00","slug":"orientierung-im-gesundheitssystem","status":"publish","type":"tribe_events","link":"https:\/\/bamigra.de\/fa\/veranstaltung\/orientierung-im-gesundheitssystem\/","title":{"rendered":"Orientierung im Gesundheitssystem"},"content":{"rendered":"<div class=\"tribe-events-single-event-description tribe-events-content\">\n<p>Orientierung im Gesundheitssystem \u2013 Einladung zur Informationsveranstaltung<\/p>\n<p>&nbsp;<\/p>\n<p>Welche\u00a0Krankenversicherung\u00a0passt\u00a0zu\u00a0mir?<br \/>\nWas\u00a0muss\u00a0ich\u00a0im\u00a0Krankenhaus,\u00a0beim\u00a0Arzt\u00a0oder\u00a0in\u00a0der\u00a0Apotheke\u00a0beachten?<br \/>\nWelche Rechte habe ich und welche Vorteile bietet mir das Gesundheitssystem?<\/p>\n<p>&nbsp;<\/p>\n<p>Antworten auf diese und weitere Fragen erhalten Sie bei unserer Infoveranstaltung. Im Rahmen des MiMi-Projekts stellen erfahrene und qualifizierte Dozent:innen wertvolle Informationen und praktische Ratschl\u00e4ge zu verschiedenen Themen rund um das Gesundheitssystem bereit.<\/p>\n<p>&nbsp;<\/p>\n<p>\ud83d\udcc5\u00a0Samstag,\u00a025.01.2025,\u00a014:00\u00a0\u2013\u00a016:00\u00a0Uhr<br \/>\n\ud83d\udccd\u00a0Blaue\u00a0Frieda,\u00a0Sch\u00fctzenstra\u00dfe\u00a02a<\/p>\n<p>&nbsp;<\/p>\n<p>Ohne\u00a0Anmeldung\u00a0und\u00a0kostenfrei.<br \/>\nWir\u00a0freuen\u00a0uns\u00a0auf\u00a0Ihre\u00a0Teilnahme!<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Erfahrene und qualifizierte Dozent:innen stellen wertvolle Informationen und praktische Ratschl\u00e4ge zu verschiedenen Themen rund um das Gesundheitssystem bereit.<\/p>\n","protected":false},"author":4,"featured_media":29860,"template":"","meta":{"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"TEC\\Tickets\\Commerce\\Module","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"_tribe_events_status":"","_tribe_events_status_reason":"","_tribe_events_is_hybrid":"","_tribe_events_is_virtual":"","_tribe_events_virtual_video_source":"","_tribe_events_virtual_embed_video":"","_tribe_events_virtual_linked_button_text":"","_tribe_events_virtual_linked_button":"","_tribe_events_virtual_show_embed_at":"","_tribe_events_virtual_show_embed_to":[],"_tribe_events_virtual_show_on_event":"","_tribe_events_virtual_show_on_views":"","_tribe_events_virtual_url":"","footnotes":"","_tec_slr_enabled":"","_tec_slr_layout":""},"tags":[],"tribe_events_cat":[110,136],"class_list":["post-29859","tribe_events","type-tribe_events","status-publish","has-post-thumbnail","hentry","tribe_events_cat-gesundheit","tribe_events_cat-information","cat_gesundheit","cat_information"],"ticketed":false,"_links":{"self":[{"href":"https:\/\/bamigra.de\/fa\/wp-json\/wp\/v2\/tribe_events\/29859","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bamigra.de\/fa\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/bamigra.de\/fa\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/bamigra.de\/fa\/wp-json\/wp\/v2\/users\/4"}],"version-history":[{"count":0,"href":"https:\/\/bamigra.de\/fa\/wp-json\/wp\/v2\/tribe_events\/29859\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bamigra.de\/fa\/wp-json\/wp\/v2\/media\/29860"}],"wp:attachment":[{"href":"https:\/\/bamigra.de\/fa\/wp-json\/wp\/v2\/media?parent=29859"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bamigra.de\/fa\/wp-json\/wp\/v2\/tags?post=29859"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/bamigra.de\/fa\/wp-json\/wp\/v2\/tribe_events_cat?post=29859"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}