{"id":26076,"date":"2024-01-30T08:29:59","date_gmt":"2024-01-30T07:29:59","guid":{"rendered":"https:\/\/bamigra.de\/veranstaltung\/interkulinarisches-kochen-in-der-blauen-frieda-6\/"},"modified":"2024-01-30T08:30:11","modified_gmt":"2024-01-30T07:30:11","slug":"interkulinarisches-kochen-in-der-blauen-frieda-5-2","status":"publish","type":"tribe_events","link":"https:\/\/bamigra.de\/fa\/veranstaltung\/interkulinarisches-kochen-in-der-blauen-frieda-5-2\/","title":{"rendered":"Interkulinarisches Kochen in der Blauen Frieda"},"content":{"rendered":"<p>Gemeinsam bereiten wir beim interkulinarischen Kochen K\u00f6stlichkeiten aus unterschiedlichen L\u00e4ndern zu.<\/p>\n<p>&nbsp;<\/p>\n<p>Dazu gibt es spannende Geschichten aus der Heimat und der Kultur der K\u00f6chin\/des Koches.<\/p>\n<p>&nbsp;<\/p>\n<p>Da die Pl\u00e4tze begrenzt sind und damit wir alles in der richtigen Menge besorgen k\u00f6nnen, bitten wir unbedingt um vorherige Anmeldung bis sp\u00e4testens Donnerstag unter: <a href=\"mailto:kontakt@freundstattfremd.de\">kontakt@freundstattfremd.de<\/a><\/p>\n<p>&nbsp;<\/p>\n<p>Wir freuen uns auf einen sch\u00f6nen, gemeinsamen Abend und laden zum Mitmachen ein!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Gemeinsam bereiten wir beim interkulinarischen Kochen K\u00f6stlichkeiten aus unterschiedlichen L\u00e4ndern zu.<\/p>\n","protected":false},"author":4,"featured_media":16721,"template":"","meta":{"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"_tribe_events_status":"","_tribe_events_status_reason":"","_tribe_events_is_hybrid":"","_tribe_events_is_virtual":"","_tribe_events_virtual_video_source":"","_tribe_events_virtual_embed_video":"","_tribe_events_virtual_linked_button_text":"","_tribe_events_virtual_linked_button":"","_tribe_events_virtual_show_embed_at":"","_tribe_events_virtual_show_embed_to":[],"_tribe_events_virtual_show_on_event":"","_tribe_events_virtual_show_on_views":"","_tribe_events_virtual_url":"","footnotes":"","_tec_slr_enabled":"","_tec_slr_layout":""},"tags":[],"tribe_events_cat":[77,99],"class_list":["post-26076","tribe_events","type-tribe_events","status-publish","has-post-thumbnail","hentry","tribe_events_cat-freizeit","tribe_events_cat-kochen","cat_freizeit","cat_kochen"],"ticketed":false,"_links":{"self":[{"href":"https:\/\/bamigra.de\/fa\/wp-json\/wp\/v2\/tribe_events\/26076","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bamigra.de\/fa\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/bamigra.de\/fa\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/bamigra.de\/fa\/wp-json\/wp\/v2\/users\/4"}],"version-history":[{"count":0,"href":"https:\/\/bamigra.de\/fa\/wp-json\/wp\/v2\/tribe_events\/26076\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bamigra.de\/fa\/wp-json\/wp\/v2\/media\/16721"}],"wp:attachment":[{"href":"https:\/\/bamigra.de\/fa\/wp-json\/wp\/v2\/media?parent=26076"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bamigra.de\/fa\/wp-json\/wp\/v2\/tags?post=26076"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/bamigra.de\/fa\/wp-json\/wp\/v2\/tribe_events_cat?post=26076"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}