{"id":10003617,"date":"2024-01-20T14:48:07","date_gmt":"2024-01-20T13:48:07","guid":{"rendered":"https:\/\/bamigra.de\/?post_type=tribe_events&#038;p=26035"},"modified":"2024-01-20T14:48:07","modified_gmt":"2024-01-20T13:48:07","slug":"cafe-blaue-frieda-12","status":"publish","type":"tribe_events","link":"https:\/\/bamigra.de\/fa\/veranstaltung\/cafe-blaue-frieda-12\/2024-02-01\/","title":{"rendered":"Caf\u00e9 Blaue Frieda"},"content":{"rendered":"<p>Das Caf\u00e9 Blaue Frieda bietet die M\u00f6glichkeit, Menschen aus verschiedenen Kulturen und Nationalit\u00e4ten kennenzulernen. Oder im Gespr\u00e4ch Deutsch zu \u00fcben und die Sprachkenntnisse dadurch zu verbessern.<\/p>\n<p>&nbsp;<\/p>\n<p>Dabei k\u00f6nnt Ihr Kaffee, Tee oder Kekse gegen Spenden konsumieren.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Kommt gerne vorbei! Wir freuen uns auf Euren Besuch!<\/strong><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Das Caf\u00e9 Blaue Frieda bietet die M\u00f6glichkeit, Menschen aus verschiedenen Kulturen und Nationalit\u00e4ten kennenzulernen. Oder im Gespr\u00e4ch Deutsch zu \u00fcben und die Sprachkenntnisse dadurch zu verbessern. &nbsp; Dabei k\u00f6nnt Ihr [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":26036,"template":"","meta":{"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"TEC\\Tickets\\Commerce\\Module","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"_tribe_events_status":"","_tribe_events_status_reason":"","_tribe_events_is_hybrid":"","_tribe_events_is_virtual":"","_tribe_events_virtual_video_source":"","_tribe_events_virtual_embed_video":"","_tribe_events_virtual_linked_button_text":"","_tribe_events_virtual_linked_button":"","_tribe_events_virtual_show_embed_at":"","_tribe_events_virtual_show_embed_to":[],"_tribe_events_virtual_show_on_event":"","_tribe_events_virtual_show_on_views":"","_tribe_events_virtual_url":"","footnotes":"","_tec_slr_enabled":"","_tec_slr_layout":""},"tags":[],"tribe_events_cat":[77],"class_list":["post-10003617","tribe_events","type-tribe_events","status-publish","has-post-thumbnail","hentry","tribe_events_cat-freizeit","cat_freizeit","tribe-recurring-event","tribe-recurring-event-parent"],"ticketed":false,"_links":{"self":[{"href":"https:\/\/bamigra.de\/fa\/wp-json\/wp\/v2\/tribe_events\/10003617","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bamigra.de\/fa\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/bamigra.de\/fa\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/bamigra.de\/fa\/wp-json\/wp\/v2\/users\/4"}],"version-history":[{"count":0,"href":"https:\/\/bamigra.de\/fa\/wp-json\/wp\/v2\/tribe_events\/10003617\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bamigra.de\/fa\/wp-json\/wp\/v2\/media\/26036"}],"wp:attachment":[{"href":"https:\/\/bamigra.de\/fa\/wp-json\/wp\/v2\/media?parent=10003617"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bamigra.de\/fa\/wp-json\/wp\/v2\/tags?post=10003617"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/bamigra.de\/fa\/wp-json\/wp\/v2\/tribe_events_cat?post=10003617"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}