{"id":10003372,"date":"2024-01-03T18:48:04","date_gmt":"2024-01-03T17:48:04","guid":{"rendered":"https:\/\/bamigra.de\/?post_type=tribe_events&#038;p=25946"},"modified":"2024-01-03T18:48:04","modified_gmt":"2024-01-03T17:48:04","slug":"sprachcafe-in-der-blauen-frieda-4","status":"publish","type":"tribe_events","link":"https:\/\/bamigra.de\/fa\/veranstaltung\/sprachcafe-in-der-blauen-frieda-4\/2024-02-02\/","title":{"rendered":"Sprachcaf\u00e9 in der Blauen Frieda"},"content":{"rendered":"<p>Sprachcaf\u00e9 in der Blauen Frieda &#8211; Deutschlernen mit Kaffee und Kuchen<\/p>\n<p>&nbsp;<\/p>\n<ul>\n<li>Du willst gerne Leute treffen und Deutsch \u00fcben?<\/li>\n<li>Du m\u00f6chtest etwas \u00fcber andere Kulturen lernen?<\/li>\n<li>Dann komm ins Sprachcaf\u00e9!<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>Wir sprechen \u00fcber Familie, Essen, Kunst, Kultur, das Leben in Deutschland und alles, wozu wir Lust haben. Alle offenen Menschen, die andere Menschen und Kulturen kennenlernen wollen, sind herzlich willkommen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Deutschlernen mit Kaffee und Kuchen<\/p>\n","protected":false},"author":4,"featured_media":14322,"template":"","meta":{"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"TEC\\Tickets\\Commerce\\Module","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"_tribe_events_status":"","_tribe_events_status_reason":"","_tribe_events_is_hybrid":"","_tribe_events_is_virtual":"","_tribe_events_virtual_video_source":"","_tribe_events_virtual_embed_video":"","_tribe_events_virtual_linked_button_text":"","_tribe_events_virtual_linked_button":"","_tribe_events_virtual_show_embed_at":"","_tribe_events_virtual_show_embed_to":[],"_tribe_events_virtual_show_on_event":"","_tribe_events_virtual_show_on_views":"","_tribe_events_virtual_url":"","footnotes":"","_tec_slr_enabled":"","_tec_slr_layout":""},"tags":[],"tribe_events_cat":[109,77,108],"class_list":["post-10003372","tribe_events","type-tribe_events","status-publish","has-post-thumbnail","hentry","tribe_events_cat-bildung","tribe_events_cat-freizeit","tribe_events_cat-sprache","cat_bildung","cat_freizeit","cat_sprache","tribe-recurring-event","tribe-recurring-event-parent"],"ticketed":false,"_links":{"self":[{"href":"https:\/\/bamigra.de\/fa\/wp-json\/wp\/v2\/tribe_events\/10003372","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bamigra.de\/fa\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/bamigra.de\/fa\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/bamigra.de\/fa\/wp-json\/wp\/v2\/users\/4"}],"version-history":[{"count":0,"href":"https:\/\/bamigra.de\/fa\/wp-json\/wp\/v2\/tribe_events\/10003372\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bamigra.de\/fa\/wp-json\/wp\/v2\/media\/14322"}],"wp:attachment":[{"href":"https:\/\/bamigra.de\/fa\/wp-json\/wp\/v2\/media?parent=10003372"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bamigra.de\/fa\/wp-json\/wp\/v2\/tags?post=10003372"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/bamigra.de\/fa\/wp-json\/wp\/v2\/tribe_events_cat?post=10003372"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}