{"id":10006181,"date":"2025-12-26T17:49:28","date_gmt":"2025-12-26T16:49:28","guid":{"rendered":"https:\/\/bamigra.de\/?post_type=tribe_events&#038;p=32528"},"modified":"2025-12-26T17:49:28","modified_gmt":"2025-12-26T16:49:28","slug":"sprechstunde-digitale-hilfe-in-der-blauen-frieda-5","status":"publish","type":"tribe_events","link":"https:\/\/bamigra.de\/en\/veranstaltung\/sprechstunde-digitale-hilfe-in-der-blauen-frieda-5\/2026-11-11\/","title":{"rendered":"Sprechstunde: digitale Hilfe in der Blauen Frieda"},"content":{"rendered":"<p>Sie haben keinen Laptop, kein Internet, keinen Drucker? Kommen Sie in die &#8220;Blaue Frieda&#8221;. Hier k\u00f6nnen Sie alle Ger\u00e4te benutzen.<\/p>\n<p>&nbsp;<\/p>\n<p>Wir helfen auch, wenn Sie Dinge am Computer machen wollen.<\/p>\n<p>&nbsp;<\/p>\n<ul>\n<li>Formulare ausf\u00fcllen<\/li>\n<li>Lebenslauf schreiben<\/li>\n<li>Drucken<\/li>\n<li>Wohnung suchen<\/li>\n<li>Termin im Rathaus vereinbaren<\/li>\n<li>Scannen<\/li>\n<li>und viele andere Dinge.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>Kommen Sie einfach &#8211; wir helfen Ihnen!<\/p>\n<p>Das Projekt wird gef\u00f6rdert von der Deutschen Stiftung f\u00fcr Ehrenamt und Engagement.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>F\u00fcr alle Fragen rund um den Computer und das Internet, k\u00f6nnt ihr zu uns kommen. Laptop, Drucker und alles, was es sonst so braucht, gibt es bei uns.<\/p>\n","protected":false},"author":4,"featured_media":29909,"template":"","meta":{"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"TEC\\Tickets\\Commerce\\Module","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"_tribe_events_status":"","_tribe_events_status_reason":"","_tribe_events_is_hybrid":"","_tribe_events_is_virtual":"","_tribe_events_virtual_video_source":"","_tribe_events_virtual_embed_video":"","_tribe_events_virtual_linked_button_text":"","_tribe_events_virtual_linked_button":"","_tribe_events_virtual_show_embed_at":"","_tribe_events_virtual_show_embed_to":[],"_tribe_events_virtual_show_on_event":"","_tribe_events_virtual_show_on_views":"","_tribe_events_virtual_url":"","footnotes":"","_tec_slr_enabled":"","_tec_slr_layout":""},"tags":[],"tribe_events_cat":[111,100,93],"class_list":["post-10006181","tribe_events","type-tribe_events","status-publish","has-post-thumbnail","hentry","tribe_events_cat-beratung","tribe_events_cat-computer","tribe_events_cat-sprechstunde","cat_beratung","cat_computer","cat_sprechstunde","tribe-recurring-event","tribe-recurring-event-parent"],"ticketed":false,"_links":{"self":[{"href":"https:\/\/bamigra.de\/en\/wp-json\/wp\/v2\/tribe_events\/10006181","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bamigra.de\/en\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/bamigra.de\/en\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/bamigra.de\/en\/wp-json\/wp\/v2\/users\/4"}],"version-history":[{"count":0,"href":"https:\/\/bamigra.de\/en\/wp-json\/wp\/v2\/tribe_events\/10006181\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bamigra.de\/en\/wp-json\/wp\/v2\/media\/29909"}],"wp:attachment":[{"href":"https:\/\/bamigra.de\/en\/wp-json\/wp\/v2\/media?parent=10006181"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bamigra.de\/en\/wp-json\/wp\/v2\/tags?post=10006181"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/bamigra.de\/en\/wp-json\/wp\/v2\/tribe_events_cat?post=10006181"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}