{"id":10006054,"date":"2025-12-26T15:11:28","date_gmt":"2025-12-26T14:11:28","guid":{"rendered":"https:\/\/bamigra.de\/?post_type=tribe_events&#038;p=32518"},"modified":"2025-12-26T15:11:28","modified_gmt":"2025-12-26T14:11:28","slug":"beratungssprechstunde-fuer-gefluechtete-in-der-blauen-frieda-2","status":"publish","type":"tribe_events","link":"https:\/\/bamigra.de\/en\/veranstaltung\/beratungssprechstunde-fuer-gefluechtete-in-der-blauen-frieda-2\/2026-11-07\/","title":{"rendered":"Beratungssprechstunde f\u00fcr Gefl\u00fcchtete in der Blauen Frieda"},"content":{"rendered":"<p>Sie haben ein Problem und brauchen Hilfe?<\/p>\n<p>Oder haben Fragen zu einem amtlichen Bescheid?<\/p>\n<p>Am Samstag geht es in der Sprechstunde um alle Fragen, die das Bleiben in Deutschland betreffen.<\/p>\n<p>&nbsp;<\/p>\n<p>Kommen Sie vorbei und bringen Ihre Fragen mit! Auch ohne Anmeldung oder Termin.<br \/>\nBitte Unterlagen vollst\u00e4ndig mitbringen.<\/p>\n<p>&nbsp;<\/p>\n<p>Die Pr\u00e4senzsprechstunde findet <strong>jeden Samstag 15:00-17:00 Uhr<\/strong> in der <em>Blauen Frieda<\/em> statt.<br \/>\nDas Sprechstundenteam ist auch telefonisch unter 0951-2975 122 oder per E-Mail an <a href=\"http:\/\/sprechstunde@freundstattfremd.de\/\">sprechstunde@freundstattfremd.de<\/a> zu erreichen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Am Samstag geht es in der Sprechstunde um alle Fragen, die das Bleiben in Deutschland betreffen.<\/p>\n","protected":false},"author":4,"featured_media":29919,"template":"","meta":{"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"TEC\\Tickets\\Commerce\\Module","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"_tribe_events_status":"","_tribe_events_status_reason":"","_tribe_events_is_hybrid":"","_tribe_events_is_virtual":"","_tribe_events_virtual_video_source":"","_tribe_events_virtual_embed_video":"","_tribe_events_virtual_linked_button_text":"","_tribe_events_virtual_linked_button":"","_tribe_events_virtual_show_embed_at":"","_tribe_events_virtual_show_embed_to":[],"_tribe_events_virtual_show_on_event":"","_tribe_events_virtual_show_on_views":"","_tribe_events_virtual_url":"","footnotes":"","_tec_slr_enabled":"","_tec_slr_layout":""},"tags":[],"tribe_events_cat":[111,93],"class_list":["post-10006054","tribe_events","type-tribe_events","status-publish","has-post-thumbnail","hentry","tribe_events_cat-beratung","tribe_events_cat-sprechstunde","cat_beratung","cat_sprechstunde","tribe-recurring-event","tribe-recurring-event-parent"],"ticketed":false,"_links":{"self":[{"href":"https:\/\/bamigra.de\/en\/wp-json\/wp\/v2\/tribe_events\/10006054","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bamigra.de\/en\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/bamigra.de\/en\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/bamigra.de\/en\/wp-json\/wp\/v2\/users\/4"}],"version-history":[{"count":0,"href":"https:\/\/bamigra.de\/en\/wp-json\/wp\/v2\/tribe_events\/10006054\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bamigra.de\/en\/wp-json\/wp\/v2\/media\/29919"}],"wp:attachment":[{"href":"https:\/\/bamigra.de\/en\/wp-json\/wp\/v2\/media?parent=10006054"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bamigra.de\/en\/wp-json\/wp\/v2\/tags?post=10006054"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/bamigra.de\/en\/wp-json\/wp\/v2\/tribe_events_cat?post=10006054"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}