{"id":10004223,"date":"2025-01-02T13:35:04","date_gmt":"2025-01-02T12:35:04","guid":{"rendered":"https:\/\/bamigra.de\/?post_type=tribe_events&#038;p=29834"},"modified":"2025-01-02T13:35:04","modified_gmt":"2025-01-02T12:35:04","slug":"schach-spielen-in-der-blauen-frieda","status":"publish","type":"tribe_events","link":"https:\/\/bamigra.de\/ar\/veranstaltung\/schach-spielen-in-der-blauen-frieda\/2025-11-10\/","title":{"rendered":"Schach spielen in der Blauen Frieda"},"content":{"rendered":"<p><strong>Jeden Montag von 18:00 bis 21:00 Uhr laden wir euch herzlich zu unserem Schachabend in der Blauen Frieda, Sch\u00fctzenstra\u00dfe 2a ein.<\/strong><\/p>\n<p>Egal, ob du schon ein erfahrener Spieler bist oder das Schachspiel erst noch lernen m\u00f6chtest \u2013 bei uns bist du genau richtig! In einer entspannten und freundlichen Atmosph\u00e4re treffen sich Anf\u00e4nger und Fortgeschrittene, um gemeinsam spannende Partien zu spielen und dabei jede Menge Spa\u00df zu haben.<\/p>\n<p>Alle sind herzlich willkommen!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Jeden Montag von 18:00 bis 21:00 Uhr Schachabend in der Blauen Frieda,<\/p>\n","protected":false},"author":4,"featured_media":29835,"template":"","meta":{"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"TEC\\Tickets\\Commerce\\Module","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"_tribe_events_status":"","_tribe_events_status_reason":"","_tribe_events_is_hybrid":"","_tribe_events_is_virtual":"","_tribe_events_virtual_video_source":"","_tribe_events_virtual_embed_video":"","_tribe_events_virtual_linked_button_text":"","_tribe_events_virtual_linked_button":"","_tribe_events_virtual_show_embed_at":"","_tribe_events_virtual_show_embed_to":[],"_tribe_events_virtual_show_on_event":"","_tribe_events_virtual_show_on_views":"","_tribe_events_virtual_url":"","footnotes":"","_tec_slr_enabled":"","_tec_slr_layout":""},"tags":[],"tribe_events_cat":[114,77],"class_list":["post-10004223","tribe_events","type-tribe_events","status-publish","has-post-thumbnail","hentry","tribe_events_cat-begegnung","tribe_events_cat-freizeit","cat_begegnung","cat_freizeit","tribe-recurring-event","tribe-recurring-event-parent"],"ticketed":false,"_links":{"self":[{"href":"https:\/\/bamigra.de\/ar\/wp-json\/wp\/v2\/tribe_events\/10004223","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bamigra.de\/ar\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/bamigra.de\/ar\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/bamigra.de\/ar\/wp-json\/wp\/v2\/users\/4"}],"version-history":[{"count":0,"href":"https:\/\/bamigra.de\/ar\/wp-json\/wp\/v2\/tribe_events\/10004223\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bamigra.de\/ar\/wp-json\/wp\/v2\/media\/29835"}],"wp:attachment":[{"href":"https:\/\/bamigra.de\/ar\/wp-json\/wp\/v2\/media?parent=10004223"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bamigra.de\/ar\/wp-json\/wp\/v2\/tags?post=10004223"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/bamigra.de\/ar\/wp-json\/wp\/v2\/tribe_events_cat?post=10004223"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}